{"id":127591,"date":"2022-05-07T17:55:16","date_gmt":"2022-05-07T17:55:16","guid":{"rendered":"https:\/\/lighthouselocarno.ch\/prodotti\/tischset-mit-bestecktasche-und-kristallen\/"},"modified":"2025-05-23T13:33:00","modified_gmt":"2025-05-23T13:33:00","slug":"tischset-mit-taschenhaltern-und-kristallen","status":"publish","type":"product","link":"https:\/\/lighthouselocarno.ch\/de\/produkt\/tischset-mit-taschenhaltern-und-kristallen\/","title":{"rendered":"Tischset mit Bestecktasche und Kristallen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><span data-sheets-value=\"{\"1\":2,\"2\":\"Tovaglietta nera in lino con porta posate decorata con cristallo. Misure 40x60 cm.\"}\" data-sheets-userformat=\"{\"2\":963,\"3\":{\"1\":0},\"4\":[null,2,16043212],\"9\":1,\"10\":1,\"11\":4,\"12\":0}\">Tischset aus Leinen mit Bestecktasche, verziert mit Kristallen. Ma\u00dfe 45&#215;70 cm.<\/span><\/p>\n<p>In Italien hergestelltes Tischset aus 100 % hochwertigem Leinen, das sich durch spezielle Behandlungen, die das nat\u00fcrliche Aussehen verst\u00e4rken, weich anf\u00fchlt.<\/p>\n<p>Dieser Stoff ist ideal f\u00fcr den Tisch, da er hypoallergen und antibakteriell ist. Au\u00dferdem werden nat\u00fcrliche und hypoallergene Farbstoffe verwendet, die der Naturfaser Glanz und Schwung verleihen.<\/p>\n<p>Langlebigkeit und einfache Wartung sind weitere Pluspunkte Ihrer Wahl.<\/p>\n<p>Ideal zur Versch\u00f6nerung Ihrer \u201emise en place\u201c: allein oder in Kombination mit L\u00e4ufern und Servietten, um immer wieder originelle Kombinationen zu schaffen.<\/p>\n<p>Bitte lesen Sie den Abschnitt \u201eProduktpflege\u201c f\u00fcr alle Waschanweisungen.<\/p>\n","protected":false},"featured_media":108035,"template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"product_brand":[8562],"product_cat":[3755,5850,3748],"product_tag":[6021,5700,7326,5853,5851],"class_list":{"0":"post-127591","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-arte-pura","7":"product_cat-tisch-zu-behoer","8":"product_cat-tischsets","9":"product_cat-wohnaccessoires","10":"product_tag-luxus","11":"product_tag-tabelle-de-2","12":"product_tag-table-accessories-de","13":"product_tag-tischsets","14":"product_tag-zubehor","15":"pa_colore-butter-alt-047","16":"pa_colore-schwarz-021","17":"pa_tema-luxus","19":"first","20":"instock","21":"shipping-taxable","22":"purchasable","23":"product-type-variable"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lighthouselocarno.ch\/de\/wp-json\/wp\/v2\/product\/127591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lighthouselocarno.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lighthouselocarno.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lighthouselocarno.ch\/de\/wp-json\/wp\/v2\/media\/108035"}],"wp:attachment":[{"href":"https:\/\/lighthouselocarno.ch\/de\/wp-json\/wp\/v2\/media?parent=127591"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lighthouselocarno.ch\/de\/wp-json\/wp\/v2\/product_brand?post=127591"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lighthouselocarno.ch\/de\/wp-json\/wp\/v2\/product_cat?post=127591"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lighthouselocarno.ch\/de\/wp-json\/wp\/v2\/product_tag?post=127591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}