{"id":127731,"date":"2022-05-07T18:01:22","date_gmt":"2022-05-07T18:01:22","guid":{"rendered":"https:\/\/lighthouselocarno.ch\/prodotti\/kneipenschuerze-mit-kristallen\/"},"modified":"2025-05-23T13:30:04","modified_gmt":"2025-05-23T13:30:04","slug":"schurze-muster-mit-kristallen","status":"publish","type":"product","link":"https:\/\/lighthouselocarno.ch\/de\/produkt\/schurze-muster-mit-kristallen\/","title":{"rendered":"Kneipensch\u00fcrze mit Kristallen"},"content":{"rendered":"<p>Produktpflege:<\/p>\n<p>Maschinenwaschbar bei 30-40 Grad mit milder Seife. Keinen Weichsp\u00fcler hinzuf\u00fcgen. Nicht bleichen.<br \/>\nAlle Kleidungsst\u00fccke von Arte Pura sind mit nat\u00fcrlichen Mineralpigmenten handgef\u00e4rbt.<br \/>\nEs ist m\u00f6glich, dass sie bei den ersten W\u00e4schen etwas an Farbe verlieren, was zu einem Vintage-Ton f\u00fchrt, der einzigartig f\u00fcr diese Marke ist.<br \/>\nBeim Waschen von Kleidung mit alten Farben empfehle ich dringend, bei den ersten 3-4 Waschg\u00e4ngen 1 kg Meersalz in die Waschmaschine zu geben, um die Farben gut zu fixieren.<\/p>\n<p>Stoff: 100% Leinen und Swarovski-Kristalle.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span data-sheets-value=\"{\"1\":2,\"2\":\"Grembiule nero modello pub con cristalli. Misure 90x100 cm. \"}\" data-sheets-userformat=\"{\"2\":961,\"3\":{\"1\":0},\"9\":1,\"10\":1,\"11\":4,\"12\":0}\">Kneipensch\u00fcrze mit Kristallen. Ma\u00dfe 90&#215;100 cm.<\/span><\/p>\n<p>Die Sch\u00fcrze wird in Italien aus 100% hochwertigem Leinen hergestellt und durch spezielle Behandlungen, die das nat\u00fcrliche Aussehen verst\u00e4rken, angenehm weich gemacht.<\/p>\n<p>Dieser Stoff ist ideal, weil er hypoallergen und antibakteriell ist. Au\u00dferdem werden nat\u00fcrliche, nicht allergene Farbstoffe verwendet, die der Naturfaser Glanz und Lebendigkeit verleihen.<\/p>\n<p>Langlebigkeit und einfache Wartung sind weitere Pluspunkte Ihrer Wahl.<\/p>\n<p>Bitte lesen Sie den Abschnitt \u201eProduktpflege\u201c f\u00fcr alle Waschanweisungen.<\/p>\n","protected":false},"featured_media":108419,"template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"product_brand":[8562],"product_cat":[6279,3755,3748],"product_tag":[6414,6021,6327,5700,7326,5851],"class_list":{"0":"post-127731","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-arte-pura","7":"product_cat-geschirrtucher-und-schurzen","8":"product_cat-tisch-zu-behoer","9":"product_cat-wohnaccessoires","10":"product_tag-kristalle","11":"product_tag-luxus","12":"product_tag-schurzen","13":"product_tag-tabelle-de-2","14":"product_tag-table-accessories-de","15":"product_tag-zubehor","16":"pa_colore-butter-alt-047","17":"pa_colore-schwarz-021","18":"pa_tema-luxus","20":"first","21":"instock","22":"shipping-taxable","23":"purchasable","24":"product-type-variable","25":"has-default-attributes"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lighthouselocarno.ch\/de\/wp-json\/wp\/v2\/product\/127731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lighthouselocarno.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lighthouselocarno.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lighthouselocarno.ch\/de\/wp-json\/wp\/v2\/media\/108419"}],"wp:attachment":[{"href":"https:\/\/lighthouselocarno.ch\/de\/wp-json\/wp\/v2\/media?parent=127731"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lighthouselocarno.ch\/de\/wp-json\/wp\/v2\/product_brand?post=127731"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lighthouselocarno.ch\/de\/wp-json\/wp\/v2\/product_cat?post=127731"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lighthouselocarno.ch\/de\/wp-json\/wp\/v2\/product_tag?post=127731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}